{"id":24851,"date":"2023-12-13T08:40:51","date_gmt":"2023-12-13T08:40:51","guid":{"rendered":"https:\/\/xometry.pro\/stories\/axtra-3d-printer-hps\/"},"modified":"2023-12-21T13:50:23","modified_gmt":"2023-12-21T13:50:23","slug":"axtra-imprimante-3d-hps","status":"publish","type":"stories","link":"https:\/\/xometry.pro\/fr\/temoignages\/axtra-imprimante-3d-hps\/","title":{"rendered":"Une imprimante 3D bas\u00e9e sur une technologie photosynth\u00e9tique hybride r\u00e9volutionnaire produite en 9 mois"},"content":{"rendered":"\n<p>Depuis le d\u00e9but des ann\u00e9es 2000 et les premiers balbutiements de l\u2019impression 3D \u00e0 base de photopolym\u00e8res, les clients ont toujours \u00e9t\u00e9 limit\u00e9s dans leur choix entre les technologies de st\u00e9r\u00e9olithographie (SLA) ou de traitement num\u00e9rique de la lumi\u00e8re (\u00ab Digital Light Processing\u00bb en anglais, abr\u00e9g\u00e9 en DLP, avec sa variante LCD). Un choix qui demande de faire des concessions, soit en favorisant la r\u00e9solution et la vitesse d\u2019impression (DLP \/ LCD), soit en se concentrant sur la qualit\u00e9 du grain de surface ou sur la taille de la zone d\u2019impression (SLA).&nbsp;<\/p>\n\n\n\n<p>Mais que se passerait-il si un tout nouveau genre d\u2019imprimante 3D parvenait \u00e0 combiner les avantages des technologies SLA, DLP et LCD pour ouvrir \u00e0 ses utilisateurs un monde de possibilit\u00e9s infinies ? Tel est le d\u00e9fi que l\u2019entreprise Axtra3D s\u2019est mis en t\u00eate de relever. Bas\u00e9e aux \u00c9tats-Unis et en Italie, Axtra3D est sp\u00e9cialis\u00e9e dans le d\u00e9veloppement de solutions avanc\u00e9es pour la fabrication additive. <\/p>\n\n\n\n<p>En s\u2019appuyant sur son expertise, l\u2019entreprise a commenc\u00e9 \u00e0 travailler sur un syst\u00e8me novateur, combinant les points forts des technologies SLA, DLP et LCD en une seule et unique imprimante 3D.&nbsp;<\/p>\n\n\n\n<p>Apr\u00e8s avoir discr\u00e8tement travaill\u00e9 sur ce projet jusqu\u2019au d\u00e9but du salon Formnext, Axtra3D a profit\u00e9 de cet \u00e9v\u00e8nement pour s\u2019en servir comme plateforme de lancement pour leur nouvelle imprimante 3D, Lumia, laquelle fonctionne sur le principe d\u2019une technologie photosynth\u00e9tique hybride brevet\u00e9e (\u00ab Hybrid PhotoSynthesis \u00bb en anglais, HPS en abr\u00e9g\u00e9).<\/p>\n\n\n<div id=\"pILp6ksQOl8-6a04c20c6a5fc\" data-video-id=\"pILp6ksQOl8\" class=\"ma-gdpr-youtube-wrapper\" style=\"width:700px;height:393.75px;padding-top:393.75px;\" data-new-window=\"\" data-yt-parameters=\"\"><picture class=\"ma-gdpr-youtube-thumbnail\"><source media=\"(min-width:640px)\" type=\"image\/webp\" srcset=\"\/\/xometry.pro\/wp-content\/uploads\/ma-gdpr-youtube-thumbnails\/pILp6ksQOl8\/pILp6ksQOl8_hq720.webp\"><source media=\"(min-width:640px)\" type=\"image\/jpeg\" srcset=\"\/\/xometry.pro\/wp-content\/uploads\/ma-gdpr-youtube-thumbnails\/pILp6ksQOl8\/pILp6ksQOl8_hq720.jpg\"><source media=\"(min-width:320px)\" type=\"image\/webp\" srcset=\"\/\/xometry.pro\/wp-content\/uploads\/ma-gdpr-youtube-thumbnails\/pILp6ksQOl8\/pILp6ksQOl8_sddefault.webp\"><source media=\"(min-width:320px)\" type=\"image\/jpeg\" srcset=\"\/\/xometry.pro\/wp-content\/uploads\/ma-gdpr-youtube-thumbnails\/pILp6ksQOl8\/pILp6ksQOl8_sddefault.jpg\"><source media=\"(min-width:240px)\" type=\"image\/webp\" srcset=\"\/\/xometry.pro\/wp-content\/uploads\/ma-gdpr-youtube-thumbnails\/pILp6ksQOl8\/pILp6ksQOl8_hqdefault.webp\"><source media=\"(min-width:240px)\" type=\"image\/jpeg\" srcset=\"\/\/xometry.pro\/wp-content\/uploads\/ma-gdpr-youtube-thumbnails\/pILp6ksQOl8\/pILp6ksQOl8_hqdefault.jpg\"><img decoding=\"async\" src=\"\/\/xometry.pro\/wp-content\/uploads\/ma-gdpr-youtube-thumbnails\/pILp6ksQOl8\/pILp6ksQOl8_mqdefault.jpg\" alt=\"\" title=\"\"><\/picture><svg class=\"ma-gdpr-youtube-button\"><use xlink:href=\"#ma-gdpr-youtube-play-button\"><\/use><\/svg><div class=\"ma-gdpr-youtube-notice\" style=\"font-size:.7em;\"><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-amelioration-de-l-experience-des-utilisateurs-au-jour-le-jour\"><strong>Am\u00e9lioration de l\u2019exp\u00e9rience des utilisateurs au jour le jour\u00a0<\/strong><\/h2>\n\n\n\n<p>C\u2019est au travers de technologies avanc\u00e9es et gr\u00e2ce \u00e0 la fabrication additive qu\u2019Axtra3D cherche \u00e0 am\u00e9liorer l\u2019exp\u00e9rience quotidienne des gens, et ce dans diverses industries ou pour diff\u00e9rentes applications. La nouvelle technologie HPS, d\u00e9velopp\u00e9e par leurs soins, est capable de r\u00e9aliser toutes sortes d\u2019ouvrages avec une r\u00e9solution des plus \u00e9lev\u00e9es, pour une vitesse d\u2019impression \u00e9poustouflante et un rendu de surface d\u2019une excellente qualit\u00e9, y compris pour des zones d\u2019impression \u00e9tendues.&nbsp;<\/p>\n\n\n\n<p>La nouvelle imprimante 3D Lumia, fournie par Axtra3D, est bien partie pour bouleverser tous les secteurs industriels s\u2019appuyant sur l\u2019impression 3D, qu\u2019il s\u2019agisse du secteur m\u00e9dical ou dentaire, de la fabrication automobile, de l\u2019a\u00e9rospatiale, des biens de consommation courante ou du prototypage fonctionnel. <\/p>\n\n\n\n<p>Les deux fondateurs de l\u2019entreprise, Gianni Zitelli et Praveen Tummala, sont \u00e9galement pr\u00eats \u00e0 parier que les utilisateurs les plus cr\u00e9atifs seront en mesure, gr\u00e2ce \u00e0 elle, de trouver de nouvelles applications \u00e0 l\u2019impression 3D dans un futur proche.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><div class=\"wp-block-image__wrap\"><img decoding=\"async\" width=\"1024\" height=\"713\" src=\"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/Lumia-3D-Printer-from-Axtra3D-\u00a9-Axtra3D-1024x713.webp\" alt=\"Lumia 3D Printer from Axtra3D \u00a9 Axtra3D\" class=\"wp-image-20674\" srcset=\"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/Lumia-3D-Printer-from-Axtra3D-\u00a9-Axtra3D-1024x713.webp 1024w, https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/Lumia-3D-Printer-from-Axtra3D-\u00a9-Axtra3D-300x209.webp 300w, https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/Lumia-3D-Printer-from-Axtra3D-\u00a9-Axtra3D-768x534.webp 768w, https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/Lumia-3D-Printer-from-Axtra3D-\u00a9-Axtra3D.webp 1440w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><a class=\"wp-block-image__fancy-box-button\" href=\"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/Lumia-3D-Printer-from-Axtra3D-\u00a9-Axtra3D.webp\" data-fancybox=\"gallery-24851\" data-caption=\"Imprimante 3D Lumia par Axtra3D \u00a9 Axtra3D\" aria-label=\"Ouvrir l&#039;image compl\u00e8te\"><img src=\"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/Lumia-3D-Printer-from-Axtra3D-\u00a9-Axtra3D.webp\" class=\"wp-block-image__fancy-box-button-thumbnail wp-post-image\" alt=\"\" loading=\"lazy\" decoding=\"async\"><svg class=\"wp-block-image__fancy-box-button-icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewBox=\"0 0 18 18\" fill=\"none\" aria-hidden=\"true\">\r\n               <path d=\"M0 2V6H2V2H6V0H2C0.895 0 0 0.895 0 2ZM2 12H0V16C0 17.105 0.895 18 2 18H6V16H2V12ZM16 16H12V18H16C17.105 18 18 17.105 18 16V12H16V16ZM16 0H12V2H16V6H18V2C18 0.895 17.105 0 16 0Z\" fill=\"#092C47\"\/>\r\n             <\/svg><\/a><\/div><figcaption class=\"wp-element-caption\">Imprimante 3D Lumia par Axtra3D \u00a9 Axtra3D<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-deux-sources-lumineuses-pour-un-resultat-unique-en-son-genre\"><strong>Deux sources lumineuses pour un r\u00e9sultat unique en son genre\u00a0<\/strong><\/h2>\n\n\n\n<p>L\u2019\u00e9quipe de recherche et d\u00e9veloppement d\u2019Axtra3D a d\u00e9velopp\u00e9 la technologie HPS en interne, \u00e0 partir de z\u00e9ro et en seulement neuf mois. Cette photosynth\u00e8se hybride combine deux sources lumineuses (un laser coupl\u00e9 \u00e0 une source DLP) selon un arrangement sp\u00e9cifique. L\u2019\u00e9nergie de ces deux sources est alors fusionn\u00e9e pour cr\u00e9er une nouvelle forme lumineuse, capable de tirer partie de fa\u00e7on harmonieuse (et efficace) de la puissance des sources originales.&nbsp;<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>\u00ab Dans le cas de notre technologie HPS, la r\u00e9solution est d\u00e9finie par le laser, ce qui nous permet d\u2019offrir une pr\u00e9cision sup\u00e9rieure aux technologies DLP standards, coupl\u00e9e \u00e0 une bien meilleure capacit\u00e9 de reproduction des \u00e9l\u00e9ments les plus minutieux\u00a0 \u00bb nous explique Zitelli.<\/p>\n\n\n\n<p>Gr\u00e2ce \u00e0 cette technologie unique en son genre, l\u2019imprimante 3D Lumia peut r\u00e9aliser des ouvrages de haute qualit\u00e9, avec des d\u00e9tails particuli\u00e8rement fins, assortis d\u2019une pr\u00e9cision et d\u2019une exactitude \u00e9tonnantes, tout \u00e7a de fa\u00e7on fiable et avec une bonne r\u00e9p\u00e9tabilit\u00e9. Ce proc\u00e9d\u00e9 novateur permet d\u2019imprimer des pi\u00e8ces en 3D \u00e0 la vitesses d\u2019une impression DLP\/LCD, mais avec le grain de surface d\u2019une impression SLA et la m\u00eame facilit\u00e9 \u00e0 passer sur un production \u00e0 grande \u00e9chelle, en plus d\u2019une r\u00e9solution des plus \u00e9lev\u00e9es. Les ouvrages peuvent \u00eatre imprim\u00e9s en continu et exhibent des propri\u00e9t\u00e9s isotropes.\u00a0<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><div class=\"wp-block-image__wrap\"><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/The-printing-process-of-Lumia-3D-Printer-\u00a9-Axtra3D-768x1024.webp\" alt=\"The printing process of Lumia 3D Printer \u00a9 Axtra3D\" class=\"wp-image-20686\" srcset=\"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/The-printing-process-of-Lumia-3D-Printer-\u00a9-Axtra3D-768x1024.webp 768w, https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/The-printing-process-of-Lumia-3D-Printer-\u00a9-Axtra3D-225x300.webp 225w, https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/The-printing-process-of-Lumia-3D-Printer-\u00a9-Axtra3D.webp 1080w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><a class=\"wp-block-image__fancy-box-button\" href=\"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/The-printing-process-of-Lumia-3D-Printer-\u00a9-Axtra3D.webp\" data-fancybox=\"gallery-24851\" data-caption=\"Proc\u00e9d\u00e9 d\u2019impression de l\u2019imprimante 3D Lumia \u00a9 Axtra3D\" aria-label=\"Ouvrir l&#039;image compl\u00e8te\"><img src=\"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/The-printing-process-of-Lumia-3D-Printer-\u00a9-Axtra3D.webp\" class=\"wp-block-image__fancy-box-button-thumbnail wp-post-image\" alt=\"\" loading=\"lazy\" decoding=\"async\"><svg class=\"wp-block-image__fancy-box-button-icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewBox=\"0 0 18 18\" fill=\"none\" aria-hidden=\"true\">\r\n               <path d=\"M0 2V6H2V2H6V0H2C0.895 0 0 0.895 0 2ZM2 12H0V16C0 17.105 0.895 18 2 18H6V16H2V12ZM16 16H12V18H16C17.105 18 18 17.105 18 16V12H16V16ZM16 0H12V2H16V6H18V2C18 0.895 17.105 0 16 0Z\" fill=\"#092C47\"\/>\r\n             <\/svg><\/a><\/div><figcaption class=\"wp-element-caption\">Proc\u00e9d\u00e9 d\u2019impression de l\u2019imprimante 3D Lumia \u00a9 Axtra3D<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>\u00ab Les utilisateurs ont souvent \u00e0 investir dans des traitements de surface co\u00fbteux \u00bb explique Tummala, \u00ab mais avec la r\u00e9solution offerte par la technologie HPS, et les surfaces de qualit\u00e9 qu\u2019elle peut r\u00e9aliser, il est possible d\u2019\u00e9conomiser du temps et de l\u2019argent sur chaque pi\u00e8ce imprim\u00e9e, vu qu\u2019elles n\u2019auront pas besoin de subir le moindre traitement de surface en post-usinage \u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><div class=\"wp-block-image__wrap\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/Surface-quality-comparison-between-DLP-and-HPS-\u00a9-Axtra3D-1024x576.webp\" alt=\"Surface quality comparison between DLP and HPS \u00a9 Axtra3D\" class=\"wp-image-20698\" srcset=\"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/Surface-quality-comparison-between-DLP-and-HPS-\u00a9-Axtra3D-1024x576.webp 1024w, https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/Surface-quality-comparison-between-DLP-and-HPS-\u00a9-Axtra3D-300x169.webp 300w, https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/Surface-quality-comparison-between-DLP-and-HPS-\u00a9-Axtra3D-768x432.webp 768w, https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/Surface-quality-comparison-between-DLP-and-HPS-\u00a9-Axtra3D-1536x864.webp 1536w, https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/Surface-quality-comparison-between-DLP-and-HPS-\u00a9-Axtra3D.webp 1920w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><a class=\"wp-block-image__fancy-box-button\" href=\"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/Surface-quality-comparison-between-DLP-and-HPS-\u00a9-Axtra3D.webp\" data-fancybox=\"gallery-24851\" data-caption=\"Comparaison de l\u2019\u00e9tat de surface entre les technologies DLP and HPS \u00a9 Axtra3D\" aria-label=\"Ouvrir l&#039;image compl\u00e8te\"><img src=\"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/Surface-quality-comparison-between-DLP-and-HPS-\u00a9-Axtra3D.webp\" class=\"wp-block-image__fancy-box-button-thumbnail wp-post-image\" alt=\"\" loading=\"lazy\" decoding=\"async\"><svg class=\"wp-block-image__fancy-box-button-icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewBox=\"0 0 18 18\" fill=\"none\" aria-hidden=\"true\">\r\n               <path d=\"M0 2V6H2V2H6V0H2C0.895 0 0 0.895 0 2ZM2 12H0V16C0 17.105 0.895 18 2 18H6V16H2V12ZM16 16H12V18H16C17.105 18 18 17.105 18 16V12H16V16ZM16 0H12V2H16V6H18V2C18 0.895 17.105 0 16 0Z\" fill=\"#092C47\"\/>\r\n             <\/svg><\/a><\/div><figcaption class=\"wp-element-caption\">Comparaison de l\u2019\u00e9tat de surface entre les technologies DLP and HPS \u00a9 Axtra3D<\/figcaption><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-s-approvisionner-avec-xometry-pour-accelerer-le-processus-de-fabrication\"><strong>S\u2019approvisionner avec Xometry pour acc\u00e9l\u00e9rer le processus de fabrication<\/strong><\/h2>\n\n\n\n<p>C\u2019est au d\u00e9but de l\u2019ann\u00e9e 2021 qu\u2019Axtra3D a commenc\u00e9 \u00e0 travailler sur leur projet novateur, avec pour objectif de lancer leur imprimante 3D au cours du salon Formnext, qui devait se tenir au mois de Novembre de la m\u00eame ann\u00e9e. \u00ab Nous avions estim\u00e9 qu\u2019il nous faudrait environ 18 mois pour finir un projet de cette ampleur \u00bb nous raconte Tummala. \u00ab Mais gr\u00e2ce \u00e0 notre \u00e9quipe et nos partenaires europ\u00e9ens, nous avons pu le boucler en seulement 9 mois \u00bb.<\/p>\n\n\n\n<p>Au mois d\u2019Ao\u00fbt, l\u2019\u00e9quipe italienne a proc\u00e9d\u00e9 au lancement des premi\u00e8res simulations du syst\u00e8me optique complexe, simulations qui se sont av\u00e9r\u00e9es \u00eatre un franc succ\u00e8s. Cette avanc\u00e9e a permis une acc\u00e9l\u00e9ration de l\u2019ensemble du processus de fabrication. <\/p>\n\n\n\n<p>\u00ab Il faut reconna\u00eetre que Xometry est pour beaucoup dans cette r\u00e9ussite, surtout parce qu\u2019ils ont \u00e9t\u00e9 capables de livrer pr\u00e8s de 2000 composants en 6 semaines, ce qui est un d\u00e9lai vraiment serr\u00e9 \u00bb affirme Zitelli. \u00ab Nous avons acc\u00e8s \u00e0 des ateliers CNC en Italie, mais cette solution n\u2019avait gu\u00e8re de sens pour notre entreprise. Travailler avec Xometry nous permet d\u2019\u00eatre en contact avec des milliers de fournisseurs dans le monde entier. C\u2019est la v\u00e9ritable valeur ajout\u00e9e de notre collaboration \u00bb.<\/p>\n\n\n\n<p>Afin de pouvoir finir leur projet \u00e0 temps pour le salon, Axtra3D a eu recours \u00e0 Xometry pour entreprendre la fabrication de toutes les pi\u00e8ces aluminium, usin\u00e9es en CNC, qui permettent d\u2019assembler l\u2019imprimante, et cela regroupe des pi\u00e8ces de taille tr\u00e8s r\u00e9duite (pour le syst\u00e8me lumineux) et d\u2019autres de taille plus importante (comme le socle de l\u2019imprimante). \u00ab Il nous est difficile de penser \u00e0 un autre fournisseur qui aurait \u00e9t\u00e9 en mesure de nous livrer dans les temps pour que nous puissions pr\u00e9senter le produit, et le lancer, au cours du salon Formnext \u00bb avoue Tummala.<\/p>\n\n\n\n<p>L\u2019\u00e9quipe d\u2019Axtra3D a travaill\u00e9 en \u00e9troite collaboration avec Liana Zedginidze de Xometry durant l\u2019int\u00e9gralit\u00e9 du processus de fabrication. \u00ab Nous avons une grande dette envers Liana : le soutien qu\u2019elle a apport\u00e9 \u00e0 notre projet \u00e9tait d\u00e9cisif et elle \u00e9tait toujours disponible pour nous aider. Gr\u00e2ce \u00e0 elle, nos pi\u00e8ces ont pu \u00eatre produites et livr\u00e9es dans les temps \u00bb explique Zitelli.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><div class=\"wp-block-image__wrap\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/axtra-3d-1024x683.webp\" alt=\"\" class=\"wp-image-20710\" srcset=\"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/axtra-3d-1024x683.webp 1024w, https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/axtra-3d-300x200.webp 300w, https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/axtra-3d-768x513.webp 768w, https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/axtra-3d.webp 1440w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><a class=\"wp-block-image__fancy-box-button\" href=\"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/axtra-3d.webp\" data-fancybox=\"gallery-24851\" data-caption=\"\" aria-label=\"Ouvrir l&#039;image compl\u00e8te\"><img src=\"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/axtra-3d.webp\" class=\"wp-block-image__fancy-box-button-thumbnail wp-post-image\" alt=\"\" loading=\"lazy\" decoding=\"async\"><svg class=\"wp-block-image__fancy-box-button-icon\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"18\" height=\"18\" viewBox=\"0 0 18 18\" fill=\"none\" aria-hidden=\"true\">\r\n               <path d=\"M0 2V6H2V2H6V0H2C0.895 0 0 0.895 0 2ZM2 12H0V16C0 17.105 0.895 18 2 18H6V16H2V12ZM16 16H12V18H16C17.105 18 18 17.105 18 16V12H16V16ZM16 0H12V2H16V6H18V2C18 0.895 17.105 0 16 0Z\" fill=\"#092C47\"\/>\r\n             <\/svg><\/a><\/div><\/figure>\n\n\n\n<p>Mais Axtra3D n\u2019a pas l\u2019intention de s\u2019arr\u00eater en si bon chemin. Leur \u00e9quipe pr\u00e9voit de prolonger leur collaboration avec Xometry dans le but de produire 10 imprimantes 3D en version b\u00eata pour le mois de Juin, dans l\u2019optique de lancer leur produit sur le march\u00e9 industriel. Cette campagne b\u00eata tournera avec des partenaires soigneusement s\u00e9lectionn\u00e9s, et aura pour objectif de cr\u00e9er la meilleure machine possible pour leurs clients.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-pour-plus-d-informations\"><strong>Pour plus d\u2019informations\u00a0<\/strong><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-a-propos-d-axtra3d\"><strong>\u00c0 propos d\u2019Axtra3D\u00a0<\/strong><\/h3>\n\n\n\n<p>Axtra3D est une entreprise \u00e0 la pointe de la technologie, sp\u00e9cialis\u00e9e dans le d\u00e9veloppement de solutions avanc\u00e9es, \u00e0 base d\u2019opto\u00e9lectronique, pour la fabrication additive. Axtra3D se consacre \u00e0 transformer en profondeur l\u2019industrie de l\u2019impression 3D gr\u00e2ce \u00e0 leur technologie pr\u00e9curseur, laquelle permet de r\u00e9soudre les probl\u00e8mes de productivit\u00e9 et de relever les d\u00e9fis pos\u00e9s par la production, tout cela au sein de nombreux secteurs industriels, notamment la sant\u00e9 (\u00e0 la fois le domaine m\u00e9dical et les soins dentaires) et la plupart des industries manufacturi\u00e8res (conception, fabrication automobile, a\u00e9rospatiale, biens de consommation courante et&nbsp; prototypage fonctionnel).<\/p>\n\n\n\n<p><strong><strong>Pour en apprendre davantage sur Axtra3D, la technologie HPS et les imprimantes 3D Lumia<\/strong><\/strong> : <a href=\"https:\/\/www.axtra3d.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/www.axtra3d.com\/<\/a>\u00a0\u00a0<br><strong><strong>Pour contacter Gianni Zitelli (Italie)<\/strong><\/strong> : <a href=\"mailto:g.*******@*****3d.com\" data-original-string=\"AAMwCHJkLkfV0OFvRDJxzg==022VaGs8ruO8gJe0X8bxaZ85sHyuBWvsJtEhDuxiv3UOKw=\" title=\"This contact has been encoded by Anti-Spam by CleanTalk. Click to decode. To finish the decoding make sure that JavaScript is enabled in your browser.\" target=\"_blank\" rel=\"noreferrer noopener\"><span \n                data-original-string='s3F83NU\/HHEL1LQkno0O0g==022hKktVyYDExtCfxTTQHgWURaeLXWY8GVleTbMgLU+0vM='\n                class='apbct-email-encoder'\n                title='This contact has been encoded by Anti-Spam by CleanTalk. Click to decode. To finish the decoding make sure that JavaScript is enabled in your browser.'>g.<span class=\"apbct-blur\">*******<\/span>@<span class=\"apbct-blur\">*****<\/span>3d.com<\/span><\/a><br><strong><strong>Pour contacter Praveen Tummala (USA) <\/strong><\/strong>: <a href=\"mailto:p.*******@*****3d.com\" data-original-string=\"HkELA3bsUurKoZiVk\/Gu5Q==022yjikebZIlr73aESJi4pecHN9f5\/klA3vCWOa02bt70Y=\" title=\"This contact has been encoded by Anti-Spam by CleanTalk. Click to decode. To finish the decoding make sure that JavaScript is enabled in your browser.\" target=\"_blank\" rel=\"noreferrer noopener\"><span \n                data-original-string='5b6chBRVJGeXVi0w3LFW1A==022usNsv8d3Nw77oiFUjdMLEvwKtdQB56Ih0DRLKL30noM='\n                class='apbct-email-encoder'\n                title='This contact has been encoded by Anti-Spam by CleanTalk. Click to decode. To finish the decoding make sure that JavaScript is enabled in your browser.'>p.<span class=\"apbct-blur\">*******<\/span>@<span class=\"apbct-blur\">*****<\/span>3d.com<\/span><\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-a-propos-de-xometry\"><strong>\u00c0 propos de Xometry<\/strong><\/h3>\n\n\n\n<p><a href=\"https:\/\/xometry.eu\/fr\">Xometry<\/a> est le leader mondial des plateformes de fabrication industrielle \u00e0 la demande. Nous mettons \u00e0 votre disposition de vastes capacit\u00e9s de production, des devis d\u00e9livr\u00e9s en ligne instantan\u00e9ment et des prix attractifs. <\/p>\n\n\n\n<p>Gr\u00e2ce \u00e0 notre r\u00e9seau de plus de 2000 ateliers de fabrication partenaires en Europe, nous sommes capables de garantir des d\u00e9lais de fabrication rapides, tout en offrant de multiples options de fabrication au travers de nos services d\u2019<a href=\"https:\/\/xometry.eu\/fr\/usinage-cnc\/\">usinage CNC<\/a>, d\u2019<a href=\"https:\/\/xometry.eu\/en\/3d-printing\/\">impression 3D<\/a>, de <a href=\"https:\/\/xometry.eu\/fr\/production-de-pieces-de-tolerie\/\">t\u00f4lerie<\/a> et de <a href=\"https:\/\/xometry.eu\/fr\/moulage-par-injection\/\">moulage par injection<\/a>. Xometry travaille avec une client\u00e8le vari\u00e9e, comprenant aussi bien des startups que des multinationales du Fortune 100, parmi lesquelles BMW ou Bosch.<\/p>\n","protected":false},"author":50,"featured_media":20739,"comment_status":"open","ping_status":"closed","template":"","c-tag-stories":[1659],"global-tag":[1698],"class_list":["post-24851","stories","type-stories","status-publish","has-post-thumbnail","hentry","c-tag-stories-construction-de-machines","global-tag-usinage-cnc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Imprimante 3D Lumia bas\u00e9e sur la technologie HPS | Xometry Pro<\/title>\n<meta name=\"description\" content=\"L\u2019entreprise Axtra3D a d\u00e9velopp\u00e9 avec succ\u00e8s une imprimante 3D r\u00e9volutionnaire, fonctionnant sur la technologie HPS, avec l\u2019aide de Xometry\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xometry.pro\/fr\/temoignages\/axtra-imprimante-3d-hps\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Imprimante 3D Lumia bas\u00e9e sur la technologie HPS | Xometry Pro\" \/>\n<meta property=\"og:description\" content=\"L\u2019entreprise Axtra3D a d\u00e9velopp\u00e9 avec succ\u00e8s une imprimante 3D r\u00e9volutionnaire, fonctionnant sur la technologie HPS, avec l\u2019aide de Xometry\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xometry.pro\/fr\/temoignages\/axtra-imprimante-3d-hps\/\" \/>\n<meta property=\"og:site_name\" content=\"Xometry Pro\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-21T13:50:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/Lumia-3D-Printer-from-Axtra3D-\u00a9-Axtra3D-1-scaled.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1821\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xometry.pro\\\/fr\\\/temoignages\\\/axtra-imprimante-3d-hps\\\/\",\"url\":\"https:\\\/\\\/xometry.pro\\\/fr\\\/temoignages\\\/axtra-imprimante-3d-hps\\\/\",\"name\":\"Imprimante 3D Lumia bas\u00e9e sur la technologie HPS | Xometry Pro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xometry.pro\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xometry.pro\\\/fr\\\/temoignages\\\/axtra-imprimante-3d-hps\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xometry.pro\\\/fr\\\/temoignages\\\/axtra-imprimante-3d-hps\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xometry.pro\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Lumia-3D-Printer-from-Axtra3D-\u00a9-Axtra3D-1-scaled.webp\",\"datePublished\":\"2023-12-13T08:40:51+00:00\",\"dateModified\":\"2023-12-21T13:50:23+00:00\",\"description\":\"L\u2019entreprise Axtra3D a d\u00e9velopp\u00e9 avec succ\u00e8s une imprimante 3D r\u00e9volutionnaire, fonctionnant sur la technologie HPS, avec l\u2019aide de Xometry\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xometry.pro\\\/fr\\\/temoignages\\\/axtra-imprimante-3d-hps\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xometry.pro\\\/fr\\\/temoignages\\\/axtra-imprimante-3d-hps\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/xometry.pro\\\/fr\\\/temoignages\\\/axtra-imprimante-3d-hps\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xometry.pro\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Lumia-3D-Printer-from-Axtra3D-\u00a9-Axtra3D-1-scaled.webp\",\"contentUrl\":\"https:\\\/\\\/xometry.pro\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Lumia-3D-Printer-from-Axtra3D-\u00a9-Axtra3D-1-scaled.webp\",\"width\":2560,\"height\":1821,\"caption\":\"Lumia 3D Printer from Axtra3D \u00a9 Axtra3D\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xometry.pro\\\/fr\\\/temoignages\\\/axtra-imprimante-3d-hps\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/xometry.pro\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e9moignages & \u00e9tudes de cas\",\"item\":\"https:\\\/\\\/xometry.pro\\\/fr\\\/temoignages\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Une imprimante 3D bas\u00e9e sur une technologie photosynth\u00e9tique hybride r\u00e9volutionnaire produite en 9 mois\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xometry.pro\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/xometry.pro\\\/fr\\\/\",\"name\":\"Xometry Pro\",\"description\":\"Knowledge &amp; Community For Engineers &amp; Product Designers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xometry.pro\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Imprimante 3D Lumia bas\u00e9e sur la technologie HPS | Xometry Pro","description":"L\u2019entreprise Axtra3D a d\u00e9velopp\u00e9 avec succ\u00e8s une imprimante 3D r\u00e9volutionnaire, fonctionnant sur la technologie HPS, avec l\u2019aide de Xometry","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xometry.pro\/fr\/temoignages\/axtra-imprimante-3d-hps\/","og_locale":"fr_FR","og_type":"article","og_title":"Imprimante 3D Lumia bas\u00e9e sur la technologie HPS | Xometry Pro","og_description":"L\u2019entreprise Axtra3D a d\u00e9velopp\u00e9 avec succ\u00e8s une imprimante 3D r\u00e9volutionnaire, fonctionnant sur la technologie HPS, avec l\u2019aide de Xometry","og_url":"https:\/\/xometry.pro\/fr\/temoignages\/axtra-imprimante-3d-hps\/","og_site_name":"Xometry Pro","article_modified_time":"2023-12-21T13:50:23+00:00","og_image":[{"width":2560,"height":1821,"url":"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/Lumia-3D-Printer-from-Axtra3D-\u00a9-Axtra3D-1-scaled.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xometry.pro\/fr\/temoignages\/axtra-imprimante-3d-hps\/","url":"https:\/\/xometry.pro\/fr\/temoignages\/axtra-imprimante-3d-hps\/","name":"Imprimante 3D Lumia bas\u00e9e sur la technologie HPS | Xometry Pro","isPartOf":{"@id":"https:\/\/xometry.pro\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xometry.pro\/fr\/temoignages\/axtra-imprimante-3d-hps\/#primaryimage"},"image":{"@id":"https:\/\/xometry.pro\/fr\/temoignages\/axtra-imprimante-3d-hps\/#primaryimage"},"thumbnailUrl":"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/Lumia-3D-Printer-from-Axtra3D-\u00a9-Axtra3D-1-scaled.webp","datePublished":"2023-12-13T08:40:51+00:00","dateModified":"2023-12-21T13:50:23+00:00","description":"L\u2019entreprise Axtra3D a d\u00e9velopp\u00e9 avec succ\u00e8s une imprimante 3D r\u00e9volutionnaire, fonctionnant sur la technologie HPS, avec l\u2019aide de Xometry","breadcrumb":{"@id":"https:\/\/xometry.pro\/fr\/temoignages\/axtra-imprimante-3d-hps\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xometry.pro\/fr\/temoignages\/axtra-imprimante-3d-hps\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/xometry.pro\/fr\/temoignages\/axtra-imprimante-3d-hps\/#primaryimage","url":"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/Lumia-3D-Printer-from-Axtra3D-\u00a9-Axtra3D-1-scaled.webp","contentUrl":"https:\/\/xometry.pro\/wp-content\/uploads\/2023\/12\/Lumia-3D-Printer-from-Axtra3D-\u00a9-Axtra3D-1-scaled.webp","width":2560,"height":1821,"caption":"Lumia 3D Printer from Axtra3D \u00a9 Axtra3D"},{"@type":"BreadcrumbList","@id":"https:\/\/xometry.pro\/fr\/temoignages\/axtra-imprimante-3d-hps\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/xometry.pro\/fr\/"},{"@type":"ListItem","position":2,"name":"T\u00e9moignages & \u00e9tudes de cas","item":"https:\/\/xometry.pro\/fr\/temoignages\/"},{"@type":"ListItem","position":3,"name":"Une imprimante 3D bas\u00e9e sur une technologie photosynth\u00e9tique hybride r\u00e9volutionnaire produite en 9 mois"}]},{"@type":"WebSite","@id":"https:\/\/xometry.pro\/fr\/#website","url":"https:\/\/xometry.pro\/fr\/","name":"Xometry Pro","description":"Knowledge &amp; Community For Engineers &amp; Product Designers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xometry.pro\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/xometry.pro\/fr\/wp-json\/wp\/v2\/stories\/24851","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xometry.pro\/fr\/wp-json\/wp\/v2\/stories"}],"about":[{"href":"https:\/\/xometry.pro\/fr\/wp-json\/wp\/v2\/types\/stories"}],"author":[{"embeddable":true,"href":"https:\/\/xometry.pro\/fr\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/xometry.pro\/fr\/wp-json\/wp\/v2\/comments?post=24851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xometry.pro\/fr\/wp-json\/wp\/v2\/media\/20739"}],"wp:attachment":[{"href":"https:\/\/xometry.pro\/fr\/wp-json\/wp\/v2\/media?parent=24851"}],"wp:term":[{"taxonomy":"c-tag-stories","embeddable":true,"href":"https:\/\/xometry.pro\/fr\/wp-json\/wp\/v2\/c-tag-stories?post=24851"},{"taxonomy":"global-tag","embeddable":true,"href":"https:\/\/xometry.pro\/fr\/wp-json\/wp\/v2\/global-tag?post=24851"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}